{"id":27825,"date":"2026-03-10T14:10:00","date_gmt":"2026-03-10T17:10:00","guid":{"rendered":"https:\/\/tanisesabino.com.br\/vereadora\/?p=27825"},"modified":"2026-05-08T14:10:54","modified_gmt":"2026-05-08T17:10:54","slug":"vereadora-tanise-sabino-se-reune-com-comite-estadual-de-prevencao-do-suicidio","status":"publish","type":"post","link":"https:\/\/tanisesabino.com.br\/vereadora\/vereadora-tanise-sabino-se-reune-com-comite-estadual-de-prevencao-do-suicidio\/","title":{"rendered":"Vereadora Tanise Sabino se re\u00fane com Comit\u00ea Estadual de Preven\u00e7\u00e3o do Suic\u00eddio"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Na tarde do dia 10 de mar\u00e7o, a vereadora psic\u00f3loga Tanise Sabino participou de uma reuni\u00e3o com o Comit\u00ea Estadual de Preven\u00e7\u00e3o do Suic\u00eddio, no Centro Administrativo Fernando Ferrari (CAFF) sendo recebida por Bruno Moraes e por integrantes da equipe t\u00e9cnica, composta majoritariamente por psic\u00f3logos e profissionais da \u00e1rea da sa\u00fade.<br>O encontro foi marcado pela troca de experi\u00eancias e pela apresenta\u00e7\u00e3o das frentes de atua\u00e7\u00e3o do Comit\u00ea, que trabalha h\u00e1 anos com vigil\u00e2ncia, pesquisa, monitoramento de dados e desenvolvimento de estrat\u00e9gias de preven\u00e7\u00e3o e p\u00f3sven\u00e7\u00e3o. Entre os temas abordados, estiveram os desafios da subnotifica\u00e7\u00e3o de casos, a import\u00e2ncia dos dados epidemiol\u00f3gicos e o acompanhamento das fam\u00edlias impactadas pelo suic\u00eddio.<br>Durante a reuni\u00e3o, Tanise destacou a import\u00e2ncia de ampliar o olhar sobre o tema. \u201cA preven\u00e7\u00e3o do suic\u00eddio passa, sobretudo pela promo\u00e7\u00e3o da sa\u00fade mental. Precisamos falar sobre cuidado integral, v\u00ednculos, pertencimento. N\u00e3o \u00e9 apenas intervir na crise, mas atuar antes dela acontecer\u201d, afirmou.<br>Os integrantes do Comit\u00ea tamb\u00e9m compartilharam experi\u00eancias de campo, evidenciando a complexidade do tema, especialmente entre jovens. Foram relatadas mudan\u00e7as nos comportamentos de autoles\u00e3o, influenciados por din\u00e2micas sociais e pelas redes digitais, al\u00e9m da necessidade de aten\u00e7\u00e3o cont\u00ednua e qualificada por parte das institui\u00e7\u00f5es.<br>Outro ponto de destaque foi a import\u00e2ncia da considerando os impactos profundos nas fam\u00edlias e comunidades. \u201cCada situa\u00e7\u00e3o tem um contexto diferente. Uma escola, uma igreja ou uma empresa vivenciam esse processo de formas distintas, e isso exige estrat\u00e9gias espec\u00edficas de acolhimento\u201d, foi ressaltado pelos profissionais.<br>A reuni\u00e3o tamb\u00e9m abordou a articula\u00e7\u00e3o com diferentes setores da sociedade, como seguran\u00e7a p\u00fablica, educa\u00e7\u00e3o e sa\u00fade, al\u00e9m da necessidade de fortalecer redes de apoio e ampliar o di\u00e1logo com institui\u00e7\u00f5es e comunidades.<br>Tanise ainda apresentou iniciativas de seu mandato voltadas \u00e0 promo\u00e7\u00e3o da sa\u00fade mental, incluindo a\u00e7\u00f5es em escolas, igrejas e comunidades. \u201cSempre procuro abordar o tema a partir da sa\u00fade mental como um todo, para que as pessoas se sintam mais abertas ao di\u00e1logo. Quando falamos de cuidado, criamos pontes\u201d, destacou.<br>Al\u00e9m do psic\u00f3logo Bruno, participaram da reuni\u00e3o as psic\u00f3logas Ana e Claudia Weyne Cruz, e a assistente social Andrea Volkmer, que tamb\u00e9m integram o Comit\u00ea Estadual de Promo\u00e7\u00e3o da Vida e Preven\u00e7\u00e3o do Suic\u00eddio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde do dia 10 de mar\u00e7o, a vereadora psic\u00f3loga Tanise Sabino participou de uma reuni\u00e3o com o Comit\u00ea Estadual de Preven\u00e7\u00e3o do Suic\u00eddio, no Centro Administrativo Fernando Ferrari (CAFF)<\/p>\n","protected":false},"author":1,"featured_media":27824,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74,1],"tags":[],"class_list":["post-27825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fp-prevencao-ao-suicidio-e-automutilacao","category-noticias"],"_links":{"self":[{"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/posts\/27825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/comments?post=27825"}],"version-history":[{"count":1,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/posts\/27825\/revisions"}],"predecessor-version":[{"id":27826,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/posts\/27825\/revisions\/27826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/media\/27824"}],"wp:attachment":[{"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/media?parent=27825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/categories?post=27825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tanisesabino.com.br\/vereadora\/wp-json\/wp\/v2\/tags?post=27825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}